{"id":2417,"date":"2026-05-29T13:50:25","date_gmt":"2026-05-29T11:50:25","guid":{"rendered":"https:\/\/www.yechivabrunoy.com\/?post_type=page-don&#038;p=2417"},"modified":"2026-06-01T14:35:42","modified_gmt":"2026-06-01T12:35:42","slug":"payment","status":"publish","type":"page-don","link":"https:\/\/www.yechivabrunoy.com\/en\/paiement\/","title":{"rendered":"Payment Page \u2013 Brunoy Yeshiva"},"featured_media":2425,"template":"","meta":{"_acf_changed":false},"categories":[],"class_list":["post-2417","page-don","type-page-don","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Page de paiement - Y\u00e9chiva de Brunoy<\/title>\n<meta name=\"description\" content=\"Sur cette page, vous pouvez r\u00e9gler les frais de scolarit\u00e9 ainsi que tout autre service fourni par la Y\u00e9chiva de Brunoy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yechivabrunoy.com\/en\/payment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Page de paiement - Y\u00e9chiva de Brunoy\" \/>\n<meta property=\"og:description\" content=\"Sur cette page, vous pouvez r\u00e9gler les frais de scolarit\u00e9 ainsi que tout autre service fourni par la Y\u00e9chiva de Brunoy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yechivabrunoy.com\/en\/payment\/\" \/>\n<meta property=\"og:site_name\" content=\"Y\u00e9chiva Brunoy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/YeshivaBrunoy\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T12:35:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/\",\"url\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/\",\"name\":\"Page de paiement - Y\u00e9chiva de Brunoy\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg\",\"datePublished\":\"2026-05-29T11:50:25+00:00\",\"dateModified\":\"2026-06-01T12:35:42+00:00\",\"description\":\"Sur cette page, vous pouvez r\u00e9gler les frais de scolarit\u00e9 ainsi que tout autre service fourni par la Y\u00e9chiva de Brunoy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg\",\"width\":640,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/paiement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Page de paiement &#8211; Y\u00e9chiva de Brunoy\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/#website\",\"url\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/\",\"name\":\"Y\u00e9chiva Brunoy\",\"description\":\"Y\u00e9chiva Tom\u2019hei Temimim Loubavitch de Brunoy\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/#organization\",\"name\":\"Y\u00e9chiva Tom\u2019hei Temimim Loubavitch de Brunoy\",\"url\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo-yechiva-brunoy@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.yechivabrunoy.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo-yechiva-brunoy@2x.png\",\"width\":681,\"height\":1005,\"caption\":\"Y\u00e9chiva Tom\u2019hei Temimim Loubavitch de Brunoy\"},\"image\":{\"@id\":\"http:\\\/\\\/www.yechivabrunoy.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/YeshivaBrunoy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Checkout Page - Yeshiva of Brunoy","description":"On this page, you can pay tuition fees as well as any other services provided by the Yeshiva of Brunoy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yechivabrunoy.com\/en\/payment\/","og_locale":"en_US","og_type":"article","og_title":"Page de paiement - Y\u00e9chiva de Brunoy","og_description":"Sur cette page, vous pouvez r\u00e9gler les frais de scolarit\u00e9 ainsi que tout autre service fourni par la Y\u00e9chiva de Brunoy.","og_url":"https:\/\/www.yechivabrunoy.com\/en\/payment\/","og_site_name":"Y\u00e9chiva Brunoy","article_publisher":"https:\/\/www.facebook.com\/YeshivaBrunoy\/","article_modified_time":"2026-06-01T12:35:42+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.yechivabrunoy.com\/paiement\/","url":"https:\/\/www.yechivabrunoy.com\/paiement\/","name":"Checkout Page - Yeshiva of Brunoy","isPartOf":{"@id":"http:\/\/www.yechivabrunoy.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yechivabrunoy.com\/paiement\/#primaryimage"},"image":{"@id":"https:\/\/www.yechivabrunoy.com\/paiement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg","datePublished":"2026-05-29T11:50:25+00:00","dateModified":"2026-06-01T12:35:42+00:00","description":"On this page, you can pay tuition fees as well as any other services provided by the Yeshiva of Brunoy.","breadcrumb":{"@id":"https:\/\/www.yechivabrunoy.com\/paiement\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yechivabrunoy.com\/paiement\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.yechivabrunoy.com\/paiement\/#primaryimage","url":"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg","contentUrl":"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2026\/05\/Gemini_Generated_Image_8lez7w8lez7w8lez-Moyenne.jpeg","width":640,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.yechivabrunoy.com\/paiement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.yechivabrunoy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Page de paiement &#8211; Y\u00e9chiva de Brunoy"}]},{"@type":"WebSite","@id":"http:\/\/www.yechivabrunoy.com\/fr\/#website","url":"http:\/\/www.yechivabrunoy.com\/fr\/","name":"Brunoy Yeshiva","description":"Tom'hei Temimim Lubavitch Yeshiva of Brunoy","publisher":{"@id":"http:\/\/www.yechivabrunoy.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.yechivabrunoy.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/www.yechivabrunoy.com\/fr\/#organization","name":"Tom'hei Temimim Lubavitch Yeshiva of Brunoy","url":"http:\/\/www.yechivabrunoy.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.yechivabrunoy.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2024\/11\/Logo-yechiva-brunoy@2x.png","contentUrl":"https:\/\/www.yechivabrunoy.com\/wp-content\/uploads\/2024\/11\/Logo-yechiva-brunoy@2x.png","width":681,"height":1005,"caption":"Y\u00e9chiva Tom\u2019hei Temimim Loubavitch de Brunoy"},"image":{"@id":"http:\/\/www.yechivabrunoy.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/YeshivaBrunoy\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.yechivabrunoy.com\/en\/wp-json\/wp\/v2\/page-don\/2417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yechivabrunoy.com\/en\/wp-json\/wp\/v2\/page-don"}],"about":[{"href":"https:\/\/www.yechivabrunoy.com\/en\/wp-json\/wp\/v2\/types\/page-don"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yechivabrunoy.com\/en\/wp-json\/wp\/v2\/media\/2425"}],"wp:attachment":[{"href":"https:\/\/www.yechivabrunoy.com\/en\/wp-json\/wp\/v2\/media?parent=2417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yechivabrunoy.com\/en\/wp-json\/wp\/v2\/categories?post=2417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}